{"id":664,"date":"2023-03-31T08:32:01","date_gmt":"2023-03-31T08:32:01","guid":{"rendered":"https:\/\/demo.myarcadeplugin.com\/arcadexls\/puzzles\/ballz-puzzle\/"},"modified":"2023-03-31T08:32:01","modified_gmt":"2023-03-31T08:32:01","slug":"ballz-puzzle","status":"publish","type":"post","link":"https:\/\/demo.myarcadeplugin.com\/arcadexls\/puzzles\/ballz-puzzle\/","title":{"rendered":"Ballz Puzzle"},"content":{"rendered":"<p>Vise les briques et lance tes balles \u00e0 toute allure afin de les d\u00e9truire !R\u00e9cup\u00e8re le maximum de balles durant la partie pour pouvoir d\u00e9truire plus de briques plus rapidement, avant que ceux-ci touchent le bas de l&#8217;\u00e9cran.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Vise les briques et lance tes balles \u00e0 toute allure afin de les d\u00e9truire !R\u00e9cup\u00e8re le maximum de balles durant la partie pour pouvoir d\u00e9truire plus de briques plus rapidement, avant que ceux-ci touchent le bas de l&#8217;\u00e9cran.<\/p>\n","protected":false},"author":1,"featured_media":663,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17],"tags":[2],"views":495,"_links":{"self":[{"href":"https:\/\/demo.myarcadeplugin.com\/arcadexls\/wp-json\/wp\/v2\/posts\/664"}],"collection":[{"href":"https:\/\/demo.myarcadeplugin.com\/arcadexls\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/demo.myarcadeplugin.com\/arcadexls\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/demo.myarcadeplugin.com\/arcadexls\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/demo.myarcadeplugin.com\/arcadexls\/wp-json\/wp\/v2\/comments?post=664"}],"version-history":[{"count":0,"href":"https:\/\/demo.myarcadeplugin.com\/arcadexls\/wp-json\/wp\/v2\/posts\/664\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/demo.myarcadeplugin.com\/arcadexls\/wp-json\/wp\/v2\/media\/663"}],"wp:attachment":[{"href":"https:\/\/demo.myarcadeplugin.com\/arcadexls\/wp-json\/wp\/v2\/media?parent=664"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/demo.myarcadeplugin.com\/arcadexls\/wp-json\/wp\/v2\/categories?post=664"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/demo.myarcadeplugin.com\/arcadexls\/wp-json\/wp\/v2\/tags?post=664"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}